{"id":1984,"date":"2024-10-28T21:23:58","date_gmt":"2024-10-28T21:23:58","guid":{"rendered":"https:\/\/dgcert.it\/?post_type=ignition-portfolio&#038;p=1984"},"modified":"2025-05-01T14:38:33","modified_gmt":"2025-05-01T14:38:33","slug":"roma-navona","status":"publish","type":"ignition-portfolio","link":"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/","title":{"rendered":"Appartamento a Roma, Piazza Navona"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1984\" class=\"elementor elementor-1984\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b005a56 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b005a56\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a849b2f\" data-id=\"1a849b2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4aface71 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4aface71\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3309dde6\" data-id=\"3309dde6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6252b631 elementor-widget elementor-widget-heading\" data-id=\"6252b631\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servizi DGcert\u00ae su un appartamento in Piazza Navona<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-768c3c0c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"768c3c0c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-250d55df elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"250d55df\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3ee03771\" data-id=\"3ee03771\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-569784c9 elementor-widget elementor-widget-heading\" data-id=\"569784c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Servizi svolti<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61140048 elementor-widget elementor-widget-heading\" data-id=\"61140048\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dgcert.it\/servizio\/due-diligence\/\">\u2022 Due Diligence immobiliare<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-544937c elementor-widget elementor-widget-heading\" data-id=\"544937c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dgcert.it\/servizio\/studi-di-fattibilita\/\">\u2022 Studio di fattibilit\u00e0  <\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d3f50d elementor-widget elementor-widget-heading\" data-id=\"2d3f50d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dgcert.it\/servizio\/total-home-inspection\/\">\u2022 Total Home Inspection<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b7a43e elementor-widget elementor-widget-heading\" data-id=\"8b7a43e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dgcert.it\/servizio\/valutazioni-certificate\/\">\u2022 Valutazione del valore di mercato<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e5e5cf0 elementor-widget elementor-widget-spacer\" data-id=\"4e5e5cf0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f636d16 elementor-widget elementor-widget-heading\" data-id=\"5f636d16\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Location<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4495ce57 elementor-widget elementor-widget-heading\" data-id=\"4495ce57\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Roma (RM)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6baef2c1 elementor-widget elementor-widget-spacer\" data-id=\"6baef2c1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba8295c elementor-hidden-desktop elementor-widget elementor-widget-spacer\" data-id=\"ba8295c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4113556f\" data-id=\"4113556f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d7f778f elementor-widget elementor-widget-heading\" data-id=\"4d7f778f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dettagli Intervento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d15a9ed elementor-widget elementor-widget-text-editor\" data-id=\"6d15a9ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"505\" data-end=\"654\">Nel cuore di Piazza Navona, una delle piazze pi\u00f9 emblematiche di Roma, abbiamo affiancato un cliente nell\u2019acquisizione di un piccolo appartamento, reso unico dalla presenza di un balcone che affaccia direttamente sulla piazza.<\/p><p class=\"\" data-start=\"656\" data-end=\"915\">Il nostro team ha eseguito il servizio DGcert\u00ae di <strong><a href=\"https:\/\/dgcert.it\/it\/service\/due-diligence\/\">Due Diligence immobiliare<\/a><\/strong>, finalizzato all\u2019individuazione delle criticit\u00e0 urbanistiche, edilizie e catastali.<\/p><p class=\"\" data-start=\"917\" data-end=\"1252\">Abbiamo inoltre svolto la <strong><a href=\"https:\/\/dgcert.it\/it\/service\/total-home-inspection\/\">Total Home Inspection<\/a>,<\/strong> analizzando lo stato manutentivo generale dell\u2019immobile e il funzionamento degli impianti elettrico, idrico-sanitario e termico.<\/p><p class=\"\" data-start=\"917\" data-end=\"1252\">Le verifiche hanno evidenziato alcuni <strong>adeguamenti necessari<\/strong> e abbiamo stimato i relativi costi, fornendo al cliente un quadro tecnico completo prima dell\u2019acquisto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1db9fd70 elementor-widget elementor-widget-spacer\" data-id=\"1db9fd70\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a1db3ce e-flex e-con-boxed e-con e-parent\" data-id=\"a1db3ce\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-197ff21 e-con-full e-flex e-con e-child\" data-id=\"197ff21\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70bbcbb elementor-widget elementor-widget-text-editor\" data-id=\"70bbcbb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"1254\" data-end=\"1564\">A completamento dell\u2019intervento, abbiamo elaborato uno <strong><a href=\"https:\/\/dgcert.it\/it\/service\/studio-di-fattibilita\/\">Studio di Fattibilit\u00e0<\/a> <\/strong>per la trasformazione dell\u2019appartamento in casa vacanza \u00a0dotata di maggiore comfort.<\/p><p class=\"\" data-start=\"1254\" data-end=\"1564\">Infine, abbiamo redatto una\u00a0<strong><a href=\"https:\/\/dgcert.it\/it\/service\/valutazione-certificata\/\">Valutazione<\/a>\u00a0<\/strong>per determinare il valore di mercato dell\u2019immobile e supportare il cliente nella pianificazione dell\u2019investimento.<\/p><p class=\"\" data-start=\"1566\" data-end=\"1754\">Grazie ai servizi erogati, il cliente ha potuto prendere decisioni informate, minimizzando i rischi e massimizzando il valore dell\u2019operazione nel centro storico di Roma.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a6f6c6 e-con-full e-flex e-con e-child\" data-id=\"8a6f6c6\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-236b2d76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"236b2d76\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6eac24f3\" data-id=\"6eac24f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-372b406f elementor-widget elementor-widget-spacer\" data-id=\"372b406f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6054e15 elementor-widget elementor-widget-heading\" data-id=\"6054e15\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gallery <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2604f49b gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"2604f49b\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-1984 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2604f49b\" data-elementor-lightbox-title=\"Roma copped\u00e8 apartment\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTk5MCwidXJsIjoiaHR0cHM6XC9cL2RnY2VydC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL1JvbWEtY29wcGVkZS1hcGFydG1lbnQud2VicCIsInNsaWRlc2hvdyI6IjI2MDRmNDliIn0%3D\" href='https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-coppede-apartment.webp'><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-coppede-apartment.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-coppede-apartment.webp 1024w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-coppede-apartment-560x420.webp 560w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-coppede-apartment-300x225.webp 300w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-coppede-apartment-768x576.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2604f49b\" data-elementor-lightbox-title=\"ROMA NAVONA 7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzY3MiwidXJsIjoiaHR0cHM6XC9cL2RnY2VydC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL1JPTUEtTkFWT05BLTcud2VicCIsInNsaWRlc2hvdyI6IjI2MDRmNDliIn0%3D\" href='https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-7.webp'><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-7.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-7.webp 1024w, https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-7-300x225.webp 300w, https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-7-768x576.webp 768w, https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-7-560x420.webp 560w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2604f49b\" data-elementor-lightbox-title=\"ROMA NAVONA 3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzY3MCwidXJsIjoiaHR0cHM6XC9cL2RnY2VydC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL1JPTUEtTkFWT05BLTMud2VicCIsInNsaWRlc2hvdyI6IjI2MDRmNDliIn0%3D\" href='https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-3.webp'><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-3.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-3.webp 1024w, https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-3-300x225.webp 300w, https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-3-768x576.webp 768w, https:\/\/dgcert.it\/wp-content\/uploads\/2025\/05\/ROMA-NAVONA-3-560x420.webp 560w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2604f49b\" data-elementor-lightbox-title=\"Roma navona apartment_6\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAwNCwidXJsIjoiaHR0cHM6XC9cL2RnY2VydC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL1JvbWEtbmF2b25hLWFwYXJ0bWVudF82LndlYnAiLCJzbGlkZXNob3ciOiIyNjA0ZjQ5YiJ9\" href='https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_6.webp'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_6.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_6.webp 768w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_6-560x747.webp 560w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_6-225x300.webp 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2604f49b\" data-elementor-lightbox-title=\"Roma navona apartment_7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAwNiwidXJsIjoiaHR0cHM6XC9cL2RnY2VydC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL1JvbWEtbmF2b25hLWFwYXJ0bWVudF83LndlYnAiLCJzbGlkZXNob3ciOiIyNjA0ZjQ5YiJ9\" href='https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_7.webp'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_7.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_7.webp 768w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_7-560x747.webp 560w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_7-225x300.webp 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2604f49b\" data-elementor-lightbox-title=\"Roma navona apartment_1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTk5OCwidXJsIjoiaHR0cHM6XC9cL2RnY2VydC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL1JvbWEtbmF2b25hLWFwYXJ0bWVudF8xLTEud2VicCIsInNsaWRlc2hvdyI6IjI2MDRmNDliIn0%3D\" href='https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_1-1.webp'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_1-1.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_1-1.webp 768w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_1-1-560x747.webp 560w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_1-1-225x300.webp 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2604f49b\" data-elementor-lightbox-title=\"Roma navona apartment_4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAwMiwidXJsIjoiaHR0cHM6XC9cL2RnY2VydC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL1JvbWEtbmF2b25hLWFwYXJ0bWVudF80LndlYnAiLCJzbGlkZXNob3ciOiIyNjA0ZjQ5YiJ9\" href='https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_4.webp'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_4.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_4.webp 768w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_4-560x747.webp 560w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_4-225x300.webp 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2604f49b\" data-elementor-lightbox-title=\"Roma navona apartment_2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAwMCwidXJsIjoiaHR0cHM6XC9cL2RnY2VydC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL1JvbWEtbmF2b25hLWFwYXJ0bWVudF8yLndlYnAiLCJzbGlkZXNob3ciOiIyNjA0ZjQ5YiJ9\" href='https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_2.webp'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_2.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_2.webp 768w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_2-560x747.webp 560w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_2-225x300.webp 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2604f49b\" data-elementor-lightbox-title=\"Roma navona apartment_8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAwOCwidXJsIjoiaHR0cHM6XC9cL2RnY2VydC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL1JvbWEtbmF2b25hLWFwYXJ0bWVudF84LndlYnAiLCJzbGlkZXNob3ciOiIyNjA0ZjQ5YiJ9\" href='https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_8.webp'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_8.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_8.webp 768w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_8-560x747.webp 560w, https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-navona-apartment_8-225x300.webp 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bc50aca elementor-widget elementor-widget-spacer\" data-id=\"4bc50aca\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-da26d78 e-flex e-con-boxed e-con e-parent\" data-id=\"da26d78\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Roma Navona  (Rm) &#8211; Lazio<\/p>\n","protected":false},"featured_media":1990,"template":"templates\/template-fullwidth.php","ignition_portfolio_category":[13],"tipologia_servizio":[28,29,49],"class_list":["post-1984","ignition-portfolio","type-ignition-portfolio","status-publish","has-post-thumbnail","hentry","ignition_portfolio_category-appartamento","tipologia_servizio-due-diligence","tipologia_servizio-studio-di-fattibilita","tipologia_servizio-valutazione-del-valore-di-mercato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Appartamento a Roma, Piazza Navona - DGcert<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Appartamento a Roma, Piazza Navona - DGcert\" \/>\n<meta property=\"og:description\" content=\"Roma Navona (Rm) - Lazio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/\" \/>\n<meta property=\"og:site_name\" content=\"DGcert\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-01T14:38:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-coppede-apartment.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/portfolio\\\/roma-navona\\\/\",\"url\":\"https:\\\/\\\/dgcert.it\\\/it\\\/portfolio\\\/roma-navona\\\/\",\"name\":\"Appartamento a Roma, Piazza Navona - DGcert\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/portfolio\\\/roma-navona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/portfolio\\\/roma-navona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dgcert.it\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Roma-coppede-apartment.webp\",\"datePublished\":\"2024-10-28T21:23:58+00:00\",\"dateModified\":\"2025-05-01T14:38:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/portfolio\\\/roma-navona\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dgcert.it\\\/it\\\/portfolio\\\/roma-navona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/portfolio\\\/roma-navona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dgcert.it\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Roma-coppede-apartment.webp\",\"contentUrl\":\"https:\\\/\\\/dgcert.it\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Roma-coppede-apartment.webp\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/portfolio\\\/roma-navona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dgcert.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appartamento a Roma, Piazza Navona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/dgcert.it\\\/it\\\/\",\"name\":\"DGcert\",\"description\":\"La garanzia per i tuoi investimenti immobiliari\",\"publisher\":{\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dgcert.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/#organization\",\"name\":\"DGcert\",\"url\":\"https:\\\/\\\/dgcert.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dgcert.it\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-dgcert-registered-a2.webp\",\"contentUrl\":\"https:\\\/\\\/dgcert.it\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-dgcert-registered-a2.webp\",\"width\":745,\"height\":160,\"caption\":\"DGcert\"},\"image\":{\"@id\":\"https:\\\/\\\/dgcert.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Appartamento a Roma, Piazza Navona - DGcert","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/","og_locale":"it_IT","og_type":"article","og_title":"Appartamento a Roma, Piazza Navona - DGcert","og_description":"Roma Navona (Rm) - Lazio","og_url":"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/","og_site_name":"DGcert","article_modified_time":"2025-05-01T14:38:33+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-coppede-apartment.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/","url":"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/","name":"Appartamento a Roma, Piazza Navona - DGcert","isPartOf":{"@id":"https:\/\/dgcert.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/#primaryimage"},"image":{"@id":"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/#primaryimage"},"thumbnailUrl":"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-coppede-apartment.webp","datePublished":"2024-10-28T21:23:58+00:00","dateModified":"2025-05-01T14:38:33+00:00","breadcrumb":{"@id":"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/#primaryimage","url":"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-coppede-apartment.webp","contentUrl":"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/10\/Roma-coppede-apartment.webp","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/dgcert.it\/it\/portfolio\/roma-navona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dgcert.it\/it\/"},{"@type":"ListItem","position":2,"name":"Appartamento a Roma, Piazza Navona"}]},{"@type":"WebSite","@id":"https:\/\/dgcert.it\/it\/#website","url":"https:\/\/dgcert.it\/it\/","name":"DGcert","description":"La garanzia per i tuoi investimenti immobiliari","publisher":{"@id":"https:\/\/dgcert.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dgcert.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/dgcert.it\/it\/#organization","name":"DGcert","url":"https:\/\/dgcert.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dgcert.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/09\/logo-dgcert-registered-a2.webp","contentUrl":"https:\/\/dgcert.it\/wp-content\/uploads\/2024\/09\/logo-dgcert-registered-a2.webp","width":745,"height":160,"caption":"DGcert"},"image":{"@id":"https:\/\/dgcert.it\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dgcert.it\/it\/wp-json\/wp\/v2\/ignition-portfolio\/1984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dgcert.it\/it\/wp-json\/wp\/v2\/ignition-portfolio"}],"about":[{"href":"https:\/\/dgcert.it\/it\/wp-json\/wp\/v2\/types\/ignition-portfolio"}],"version-history":[{"count":38,"href":"https:\/\/dgcert.it\/it\/wp-json\/wp\/v2\/ignition-portfolio\/1984\/revisions"}],"predecessor-version":[{"id":3690,"href":"https:\/\/dgcert.it\/it\/wp-json\/wp\/v2\/ignition-portfolio\/1984\/revisions\/3690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dgcert.it\/it\/wp-json\/wp\/v2\/media\/1990"}],"wp:attachment":[{"href":"https:\/\/dgcert.it\/it\/wp-json\/wp\/v2\/media?parent=1984"}],"wp:term":[{"taxonomy":"ignition_portfolio_category","embeddable":true,"href":"https:\/\/dgcert.it\/it\/wp-json\/wp\/v2\/ignition_portfolio_category?post=1984"},{"taxonomy":"tipologia_servizio","embeddable":true,"href":"https:\/\/dgcert.it\/it\/wp-json\/wp\/v2\/tipologia_servizio?post=1984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}